{"id":4547,"date":"2023-08-02T13:12:29","date_gmt":"2023-08-02T06:12:29","guid":{"rendered":"https:\/\/htdentalart.vn\/?page_id=4547"},"modified":"2025-07-22T21:26:34","modified_gmt":"2025-07-22T14:26:34","slug":"product","status":"publish","type":"page","link":"https:\/\/htdentalart.vn\/en\/product\/","title":{"rendered":"PRODUCT"},"content":{"rendered":"\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1990104225\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"965\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/08\/Customized-Abutment.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/08\/Customized-Abutment.jpg 2560w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/08\/Customized-Abutment-300x113.jpg 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/08\/Customized-Abutment-1024x386.jpg 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/08\/Customized-Abutment-768x290.jpg 768w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/08\/Customized-Abutment-1536x579.jpg 1536w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/08\/Customized-Abutment-2048x772.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1990104225 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<section class=\"section\" id=\"section_2120291856\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:140%;\">Our products<\/span><b><\/b><\/h2><\/div>\n<div class=\"row\"  id=\"row-1892172163\">\n\n\n\t<div id=\"col-2133384461\" class=\"col hide-for-small small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-1936394985\" >\n    <div class=\"slider slider-nav-dots-dashes slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-shadow slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row\"  id=\"row-379293794\">\n\n\n\t<div id=\"col-1674587750\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:95%;\">\n\t\t\t<a href=\"https:\/\/htdentalart.vn\/en\/product\/precious-metal-restorations\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1449\" height=\"872\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2.jpg 1449w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2-300x181.jpg 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2-1024x616.jpg 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2-768x462.jpg 768w\" sizes=\"auto, (max-width: 1449px) 100vw, 1449px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.4)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-3184199144\" class=\"text\">\n\t\t\n\nPrecious Metal Restorations\n\t\t\n<style>\n#text-3184199144 {\n  font-size: 1.4rem;\n  color: rgb(255,255,255);\n}\n#text-3184199144 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/htdentalart.vn\/en\/product\/precious-metal-restorations\/\" target=\"_self\" class=\"button primary lowercase\"  >\n    <span>Discover Now<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-79271246\">\n\n\n\t<div id=\"col-1591958927\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:95%;\">\n\t\t\t<a href=\"https:\/\/htdentalart.vn\/en\/product\/stickers-inlay-onlay-overlay\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-scaled.jpg 2560w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-300x200.jpg 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-1024x683.jpg 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-768x512.jpg 768w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-1536x1024.jpg 1536w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.4)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-3971904999\" class=\"text\">\n\t\t\n\n<p>Inlay, Onlay, Overlay<\/p>\n\t\t\n<style>\n#text-3971904999 {\n  font-size: 1.4rem;\n  color: rgb(255,255,255);\n}\n#text-3971904999 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/htdentalart.vn\/en\/product\/stickers-inlay-onlay-overlay\/\" target=\"_self\" class=\"button primary lowercase\"  >\n    <span>Discover Now<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-79844395\">\n\n\n\t<div id=\"col-470109525\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:95%;\">\n\t\t\t<a href=\"https:\/\/htdentalart.vn\/en\/product\/restoration-on-implant\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"608\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1.png 1130w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1-300x161.png 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1-1024x551.png 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1-768x413.png 768w\" sizes=\"auto, (max-width: 1130px) 100vw, 1130px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.4)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-3527464952\" class=\"text\">\n\t\t\n\nRestoration on Implant\n\t\t\n<style>\n#text-3527464952 {\n  font-size: 1.4rem;\n  color: rgb(255,255,255);\n}\n#text-3527464952 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/htdentalart.vn\/en\/product\/restoration-on-implant\/\" target=\"_self\" class=\"button primary lowercase\"  >\n    <span>Discover Now<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1030658672\">\n\n\n\t<div id=\"col-1409933413\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:95%;\">\n\t\t\t<a href=\"https:\/\/htdentalart.vn\/en\/product\/cosmetic-porcelain-restoration\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-scaled.jpg 2560w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-300x200.jpg 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-1024x683.jpg 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-768x512.jpg 768w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-1536x1024.jpg 1536w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.4)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-4093781882\" class=\"text\">\n\t\t\n\nCosmetic porcelain restoration\n\t\t\n<style>\n#text-4093781882 {\n  font-size: 1.4rem;\n  color: rgb(255,255,255);\n}\n#text-4093781882 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/htdentalart.vn\/en\/product\/cosmetic-porcelain-restoration\/\" target=\"_self\" class=\"button primary lowercase\"  >\n    <span>Discover Now<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n          <style>\n            #slider-1936394985 .flickity-slider > * { max-width: 35% !important; }\n     <\/style>\n     \t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2062962433\" class=\"col show-for-small small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(0,0,0);\" >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-190200727\" >\n    <div class=\"slider slider-nav-dots-dashes slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-shadow slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row\"  id=\"row-474928605\">\n\n\n\t<div id=\"col-1022158009\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:95%;\">\n\t\t\t<a href=\"https:\/\/htdentalart.vn\/en\/product\/precious-metal-restorations\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1449\" height=\"872\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2.jpg 1449w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2-300x181.jpg 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2-1024x616.jpg 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/2-768x462.jpg 768w\" sizes=\"auto, (max-width: 1449px) 100vw, 1449px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.4)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-445188335\" class=\"text\">\n\t\t\n\nPrecious Metal Restorations\n\t\t\n<style>\n#text-445188335 {\n  font-size: 1.4rem;\n  color: rgb(255,255,255);\n}\n#text-445188335 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/htdentalart.vn\/en\/product\/precious-metal-restorations\/\/\" target=\"_self\" class=\"button primary is-outline lowercase\"  >\n    <span>Discover Now<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1109062649\">\n\n\n\t<div id=\"col-356781682\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:95%;\">\n\t\t\t<a href=\"https:\/\/htdentalart.vn\/en\/product\/stickers-inlay-onlay-overlay\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-scaled.jpg 2560w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-300x200.jpg 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-1024x683.jpg 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-768x512.jpg 768w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-1536x1024.jpg 1536w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_1622-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.4)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-69071388\" class=\"text\">\n\t\t\n\n<p>Inlay, Onlay, Overlay<\/p>\n\n\t\t\n<style>\n#text-69071388 {\n  font-size: 1.4rem;\n  color: rgb(255,255,255);\n}\n#text-69071388 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/htdentalart.vn\/en\/product\/stickers-inlay-onlay-overlay\/\" target=\"_self\" class=\"button primary lowercase\"  >\n    <span>Discover Now<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-227646037\">\n\n\n\t<div id=\"col-1156331065\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:95%;\">\n\t\t\t<a href=\"https:\/\/htdentalart.vn\/en\/product\/restoration-on-implant\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"608\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1.png 1130w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1-300x161.png 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1-1024x551.png 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/1-768x413.png 768w\" sizes=\"auto, (max-width: 1130px) 100vw, 1130px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.4)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-1107764528\" class=\"text\">\n\t\t\n\nRestoration on Implant\n\t\t\n<style>\n#text-1107764528 {\n  font-size: 1.4rem;\n  color: rgb(255,255,255);\n}\n#text-1107764528 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/htdentalart.vn\/en\/product\/restoration-on-implant\/\" target=\"_self\" class=\"button primary lowercase\"  >\n    <span>Discover Now<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1289449434\">\n\n\n\t<div id=\"col-1726999089\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:95%;\">\n\t\t\t<a href=\"https:\/\/htdentalart.vn\/en\/product\/cosmetic-porcelain-restoration\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-scaled.jpg 2560w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-300x200.jpg 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-1024x683.jpg 1024w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-768x512.jpg 768w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-1536x1024.jpg 1536w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/12\/QQQ_6370-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.4)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-2072944384\" class=\"text\">\n\t\t\n\n<p>Esthetic restoration<\/p>\n\t\t\n<style>\n#text-2072944384 {\n  font-size: 1.4rem;\n  color: rgb(255,255,255);\n}\n#text-2072944384 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/htdentalart.vn\/en\/product\/cosmetic-porcelain-restoration\/\" target=\"_self\" class=\"button primary lowercase\"  >\n    <span>Discover Now<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n          <style>\n            #slider-190200727 .flickity-slider > * { max-width: 75% !important; }\n     <\/style>\n     \t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2120291856 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(0,0,0);\n}\n#section_2120291856 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_2120291856 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_629446265\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:175%;color:rgb(255, 255, 255);\">Why choose us<\/span><b><\/b><\/h3><\/div>\n\n<div class=\"row\"  id=\"row-630880106\">\n\n\n\t<div id=\"col-476225326\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:1px;\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/iteration-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/iteration-300x300.png 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/iteration-150x150.png 150w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/iteration.png 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-4065096307\" class=\"text\">\n\t\t\n\n<h3><span style=\"color: #ffffff\"><strong>ENTIRETY<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff\">OF PROCESS<\/span><\/p>\n\t\t\n<style>\n#text-4065096307 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-774518767\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:1px;\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/value-chain-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/value-chain-300x300.png 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/value-chain-150x150.png 150w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/value-chain.png 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-3988709085\" class=\"text\">\n\t\t\n\n<h3><span style=\"color: #ffffff\"><strong>EXACTEMENT<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff\">OF SCIENCE<\/span><\/p>\n\t\t\n<style>\n#text-3988709085 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1535802332\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:1px;\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/data-synchronization-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/data-synchronization-300x300.png 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/data-synchronization-150x150.png 150w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/data-synchronization.png 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-1671880631\" class=\"text\">\n\t\t\n\n<h3><span style=\"color: #ffffff\"><strong>EXCELLENT<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff\">OF\u00a0 AESTHETICS<\/span><\/p>\n\t\t\n<style>\n#text-1671880631 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_629446265 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(0,0,0);\n}\n#section_629446265 .section-bg-overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#section_629446265 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_629446265 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section dark\" id=\"section_1010942993\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1833982338\">\n\n\n\t<div id=\"col-608307706\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:175%;color:rgb(255, 255, 255);\">Our partner<\/span><b><\/b><\/h3><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-46767984\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-1846931688\" >\n    <div class=\"slider slider-nav-dots-dashes slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"left\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 122.03883495146px!important\"><div class=\"ux-logo-link block image-glow\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/ivoclar.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:80px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 198.31683168317px!important\"><div class=\"ux-logo-link block image-glow\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/IPS-e.max-CAD.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:80px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 264.8623853211px!important\"><div class=\"ux-logo-link block image-glow\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2023\/07\/nexdent.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:80px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 295.17482517483px!important\"><div class=\"ux-logo-link block image-glow\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/straumann.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:80px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 150px!important\"><div class=\"ux-logo-link block image-glow\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/densply-sirona.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:80px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 385.90701219512px!important\"><div class=\"ux-logo-link block image-glow\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/3shape.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:75px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 213.20284697509px!important\"><div class=\"ux-logo-link block image-glow\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/R-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:80px;\" \/><\/div><\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1010942993 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(0,0,0);\n}\n#section_1010942993 .section-bg-overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#section_1010942993 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1010942993 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1021084739\">\n\t\t<div class=\"bg section-bg fill bg-fill  \" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-393820609\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-393820609 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-2038352017\">\n\n\n\t<div id=\"col-1140737231\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1431756090\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/LOGO-2-Copy.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/LOGO-2-Copy.png 1000w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/LOGO-2-Copy-300x300.png 300w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/LOGO-2-Copy-150x150.png 150w, https:\/\/htdentalart.vn\/wp-content\/uploads\/2025\/07\/LOGO-2-Copy-768x768.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1431756090 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1295316595\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4918-o1\" lang=\"vi\" dir=\"ltr\" data-wpcf7-id=\"4918\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/4547#wpcf7-f4918-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Form li\u00ean h\u1ec7\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4918\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"vi\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4918-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-flat\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"c-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"T\u00ean c\u1ee7a b\u1ea1n (*)\" value=\"\" type=\"text\" name=\"c-name\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"c-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-text wpcf7-validates-as-email\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"c-email\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"c-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"S\u1ed1 \u0111i\u1ec7n tho\u1ea1i (*)\" value=\"\" type=\"tel\" name=\"c-phone\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"c-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"N\u1ed9i dung\/Y\u00eau c\u1ea7u\" name=\"c-message\"><\/textarea><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner button\" type=\"submit\" value=\"Y\u00eau c\u1ea7u t\u01b0 v\u1ea5n ngay\" \/>\n\t<\/p>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"244\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1021084739 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1021084739 .section-bg.bg-loaded {\n  background-image: url(https:\/\/htdentalart.vn\/wp-content\/uploads\/2024\/09\/1-2.png);\n}\n#section_1021084739 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1021084739 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-4547","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/htdentalart.vn\/en\/wp-json\/wp\/v2\/pages\/4547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/htdentalart.vn\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/htdentalart.vn\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/htdentalart.vn\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/htdentalart.vn\/en\/wp-json\/wp\/v2\/comments?post=4547"}],"version-history":[{"count":1,"href":"https:\/\/htdentalart.vn\/en\/wp-json\/wp\/v2\/pages\/4547\/revisions"}],"predecessor-version":[{"id":8042,"href":"https:\/\/htdentalart.vn\/en\/wp-json\/wp\/v2\/pages\/4547\/revisions\/8042"}],"wp:attachment":[{"href":"https:\/\/htdentalart.vn\/en\/wp-json\/wp\/v2\/media?parent=4547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}